{"id":4143,"date":"2017-08-30T08:58:14","date_gmt":"2017-08-30T06:58:14","guid":{"rendered":"https:\/\/demos.welaunch.io\/woocommerce-wishlist\/?post_type=faq&#038;p=179"},"modified":"2021-11-18T13:57:08","modified_gmt":"2021-11-18T12:57:08","slug":"setup-wunschliste-plugin","status":"publish","type":"faq","link":"https:\/\/www.welaunch.io\/de\/wissensdatenbank\/faq\/setup-wunschliste-plugin\/","title":{"rendered":"WooCommerce-Wunschlisten-Plugin einrichten"},"content":{"rendered":"<p>Einfach &amp; schnell! Jetzt in wenigen Schritten unser WooCommerce Wunschzettel Plugin einrichten.<\/p>\n<h2>Men\u00fc Einstellungen<\/h2>\n<p>Um das Plugin einzurichten, sollten Sie das Wunschzettel unter dem WooCommerce-Men\u00fc sehen k\u00f6nnen. Wenn Sie das Men\u00fc Katalogmodus nicht sehen k\u00f6nnen, stellen Sie sicher, dass unser <a href=\"https:\/\/welaunch.io\/updates\/welaunch-framework.zip\" target=\"_blank\" rel=\"noopener\">weLaunch Framework Plugin<\/a> installiert und aktiviert ist.<\/p>\n<h2>Allgemeine Einstellungen<\/h2>\n<p>In den Allgemeinen Einstellungen sollten Sie zun\u00e4chst Ihre Wunschlistenseite einstellen. If you have not created a wishlist page, create one and insert the shortcode <code>[woocommerce_wishlist]<\/code> there. Dann weisen Sie es zu.Then you can also create a Wishlist search page, where the shortcode <code>[woocommerce_wishlist_search]<\/code> should be placed. Au\u00dferdem k\u00f6nnen Sie hier die Einstellung der Wunschliste der G\u00e4ste aktivieren.<\/p>\n<figure id=\"attachment_5288\" aria-describedby=\"caption-attachment-5288\" style=\"width: 1020px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-5288\" src=\"https:\/\/www.welaunch.io\/de\/wp-content\/uploads\/sites\/8\/2017\/08\/woocommerce-wishlist-general-settings-1024x719.png\" alt=\"WooCommerce-Wunschliste allgemeine Einstellungen\" width=\"1020\" height=\"716\" srcset=\"https:\/\/www.welaunch.io\/de\/wp-content\/uploads\/sites\/11\/2017\/08\/woocommerce-wishlist-general-settings-1024x719.png 1024w, https:\/\/www.welaunch.io\/de\/wp-content\/uploads\/sites\/11\/2017\/08\/woocommerce-wishlist-general-settings-300x211.png 300w, https:\/\/www.welaunch.io\/de\/wp-content\/uploads\/sites\/11\/2017\/08\/woocommerce-wishlist-general-settings-768x539.png 768w, https:\/\/www.welaunch.io\/de\/wp-content\/uploads\/sites\/11\/2017\/08\/woocommerce-wishlist-general-settings-500x351.png 500w, https:\/\/www.welaunch.io\/de\/wp-content\/uploads\/sites\/11\/2017\/08\/woocommerce-wishlist-general-settings-1000x702.png 1000w, https:\/\/www.welaunch.io\/de\/wp-content\/uploads\/sites\/11\/2017\/08\/woocommerce-wishlist-general-settings.png 1362w\" sizes=\"auto, (max-width: 1020px) 100vw, 1020px\" \/><figcaption id=\"caption-attachment-5288\" class=\"wp-caption-text\">WooCommerce-Wunschliste allgemeine Einstellungen<\/figcaption><\/figure>\n<h3>Schaltfl\u00e4chen-Einstellungen<\/h3>\n<p>In den Schaltfl\u00e4cheneinstellungen k\u00f6nnen Sie aktivieren\/deaktivieren und konfigurieren, in welchem WooCommerce Hook die Schaltfl\u00e4che f\u00fcr ein einzelnes Produkt oder eine Shop-Schleife platziert wird.<\/p>\n<figure id=\"attachment_5287\" aria-describedby=\"caption-attachment-5287\" style=\"width: 1020px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-5287\" src=\"https:\/\/www.welaunch.io\/de\/wp-content\/uploads\/sites\/8\/2017\/08\/wishlist-button-configuration-1024x604.png\" alt=\"Konfiguration der WooCommerce-Wunschliste\" width=\"1020\" height=\"602\" srcset=\"https:\/\/www.welaunch.io\/de\/wp-content\/uploads\/sites\/11\/2017\/08\/wishlist-button-configuration-1024x604.png 1024w, https:\/\/www.welaunch.io\/de\/wp-content\/uploads\/sites\/11\/2017\/08\/wishlist-button-configuration-300x177.png 300w, https:\/\/www.welaunch.io\/de\/wp-content\/uploads\/sites\/11\/2017\/08\/wishlist-button-configuration-768x453.png 768w, https:\/\/www.welaunch.io\/de\/wp-content\/uploads\/sites\/11\/2017\/08\/wishlist-button-configuration-500x295.png 500w, https:\/\/www.welaunch.io\/de\/wp-content\/uploads\/sites\/11\/2017\/08\/wishlist-button-configuration-1000x590.png 1000w, https:\/\/www.welaunch.io\/de\/wp-content\/uploads\/sites\/11\/2017\/08\/wishlist-button-configuration.png 1186w\" sizes=\"auto, (max-width: 1020px) 100vw, 1020px\" \/><figcaption id=\"caption-attachment-5287\" class=\"wp-caption-text\">Konfiguration der WooCommerce-Wunschliste<\/figcaption><\/figure>\n<h3>Modal &amp; Popup-Optionen<\/h3>\n<p>In der Styling-Sektion unseres Plugins k\u00f6nnen Sie einige Stylings in Bezug auf das Modal, das wir f\u00fcr das Hinzuf\u00fcgen von Wunschlistenprodukten oder die Erstellung neuer Wunschlisten verwenden, anpassen.Wenn die Stile nicht funktionieren, stellen Sie sicher, dass die folgende Datei einen CHMOD 0777 hat: \/wp-inhalt\/woocommerce-wishlist\/\u00f6ffentlich\/css\/woocommerce-wishlist-custom.css<\/p>\n<figure id=\"attachment_5284\" aria-describedby=\"caption-attachment-5284\" style=\"width: 1020px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-5284\" src=\"https:\/\/www.welaunch.io\/de\/wp-content\/uploads\/sites\/8\/2017\/08\/wishlist-styling-options-1024x585.png\" alt=\"Wunschzettel-Stylingoptionen\" width=\"1020\" height=\"583\" srcset=\"https:\/\/www.welaunch.io\/de\/wp-content\/uploads\/sites\/11\/2017\/08\/wishlist-styling-options-1024x585.png 1024w, https:\/\/www.welaunch.io\/de\/wp-content\/uploads\/sites\/11\/2017\/08\/wishlist-styling-options-300x171.png 300w, https:\/\/www.welaunch.io\/de\/wp-content\/uploads\/sites\/11\/2017\/08\/wishlist-styling-options-768x439.png 768w, https:\/\/www.welaunch.io\/de\/wp-content\/uploads\/sites\/11\/2017\/08\/wishlist-styling-options-500x286.png 500w, https:\/\/www.welaunch.io\/de\/wp-content\/uploads\/sites\/11\/2017\/08\/wishlist-styling-options-1000x572.png 1000w, https:\/\/www.welaunch.io\/de\/wp-content\/uploads\/sites\/11\/2017\/08\/wishlist-styling-options.png 1188w\" sizes=\"auto, (max-width: 1020px) 100vw, 1020px\" \/><figcaption id=\"caption-attachment-5284\" class=\"wp-caption-text\">Wunschzettel-Stylingoptionen<\/figcaption><\/figure>\n<h3>Anzuzeigende Daten<\/h3>\n<p>Der Abschnitt &#8220;Zu zeigende Daten&#8221; erm\u00f6glicht es Ihnen, bestimmte Teile des Wunschlisteninhalts zu aktivieren und zu deaktivieren. Die folgenden Elemente sind m\u00f6glich:<\/p>\n<ul>\n<li>Bild<\/li>\n<li>Galerie<\/li>\n<li>Titel<\/li>\n<li>Rezensionen<\/li>\n<li>Preis<\/li>\n<li>SKU<\/li>\n<li>Schlagw\u00f6rter<\/li>\n<li>Kategorien<\/li>\n<li>Kurze Beschreibung<\/li>\n<li>Zum Warenkorb hinzuf\u00fcgen<\/li>\n<li>Beschreibung<\/li>\n<li>Eigenschaften<\/li>\n<li>Lesen Sie mehr<\/li>\n<\/ul>\n<p>Au\u00dferdem k\u00f6nnen Sie dort den Wunschzettel Sharing aktivieren und festlegen, f\u00fcr welche Dienste das Sharing verf\u00fcgbar sein soll.<\/p>\n<figure id=\"attachment_5286\" aria-describedby=\"caption-attachment-5286\" style=\"width: 1020px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-5286\" src=\"https:\/\/www.welaunch.io\/de\/wp-content\/uploads\/sites\/8\/2017\/08\/data-to-show-in-wishlists-1024x853.png\" alt=\"Daten, die in den WooCommerce-Wunschlisten erscheinen\" width=\"1020\" height=\"850\" srcset=\"https:\/\/www.welaunch.io\/de\/wp-content\/uploads\/sites\/11\/2017\/08\/data-to-show-in-wishlists-1024x853.png 1024w, https:\/\/www.welaunch.io\/de\/wp-content\/uploads\/sites\/11\/2017\/08\/data-to-show-in-wishlists-300x250.png 300w, https:\/\/www.welaunch.io\/de\/wp-content\/uploads\/sites\/11\/2017\/08\/data-to-show-in-wishlists-768x640.png 768w, https:\/\/www.welaunch.io\/de\/wp-content\/uploads\/sites\/11\/2017\/08\/data-to-show-in-wishlists-500x417.png 500w, https:\/\/www.welaunch.io\/de\/wp-content\/uploads\/sites\/11\/2017\/08\/data-to-show-in-wishlists-1000x833.png 1000w, https:\/\/www.welaunch.io\/de\/wp-content\/uploads\/sites\/11\/2017\/08\/data-to-show-in-wishlists.png 1187w\" sizes=\"auto, (max-width: 1020px) 100vw, 1020px\" \/><figcaption id=\"caption-attachment-5286\" class=\"wp-caption-text\">Daten, die in den WooCommerce-Wunschlisten erscheinen<\/figcaption><\/figure>\n","protected":false},"author":1,"featured_media":0,"menu_order":0,"comment_status":"open","ping_status":"closed","template":"","product_cat":[],"class_list":["post-4143","faq","type-faq","status-publish","hentry","faq_topics-wunschzettel-einstieg"],"_links":{"self":[{"href":"https:\/\/www.welaunch.io\/de\/wp-json\/wp\/v2\/faq\/4143","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.welaunch.io\/de\/wp-json\/wp\/v2\/faq"}],"about":[{"href":"https:\/\/www.welaunch.io\/de\/wp-json\/wp\/v2\/types\/faq"}],"author":[{"embeddable":true,"href":"https:\/\/www.welaunch.io\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.welaunch.io\/de\/wp-json\/wp\/v2\/comments?post=4143"}],"version-history":[{"count":5,"href":"https:\/\/www.welaunch.io\/de\/wp-json\/wp\/v2\/faq\/4143\/revisions"}],"predecessor-version":[{"id":6527,"href":"https:\/\/www.welaunch.io\/de\/wp-json\/wp\/v2\/faq\/4143\/revisions\/6527"}],"wp:attachment":[{"href":"https:\/\/www.welaunch.io\/de\/wp-json\/wp\/v2\/media?parent=4143"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.welaunch.io\/de\/wp-json\/wp\/v2\/product_cat?post=4143"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}